{"id":1047,"count":1,"description":"","link":"https:\/\/blog.aqualowe.ch\/index.php\/tag\/profondeur-de-la-nuit\/","name":"profondeur de la nuit","slug":"profondeur-de-la-nuit","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/blog.aqualowe.ch\/index.php\/wp-json\/wp\/v2\/tags\/1047","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.aqualowe.ch\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/blog.aqualowe.ch\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/blog.aqualowe.ch\/index.php\/wp-json\/wp\/v2\/posts?tags=1047"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}