{"id":1111,"count":1,"description":"","link":"https:\/\/blog.aqualowe.ch\/index.php\/tag\/la-cerise-sur-le-gateau\/","name":"la cerise sur le g\u00e2teau","slug":"la-cerise-sur-le-gateau","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/blog.aqualowe.ch\/index.php\/wp-json\/wp\/v2\/tags\/1111","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.aqualowe.ch\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/blog.aqualowe.ch\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/blog.aqualowe.ch\/index.php\/wp-json\/wp\/v2\/posts?tags=1111"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}